{"id":4,"count":18,"description":"review","link":"https:\/\/overdriven.fr\/overdriven\/index.php\/category\/reviews\/","name":"Reviews","slug":"reviews","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Reviews - Overdriven.fr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/overdriven.fr\/overdriven\/index.php\/category\/reviews\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Reviews - Overdriven.fr\" \/>\n<meta property=\"og:description\" content=\"review\" \/>\n<meta property=\"og:url\" content=\"https:\/\/overdriven.fr\/overdriven\/index.php\/category\/reviews\/\" \/>\n<meta property=\"og:site_name\" content=\"Overdriven.fr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/overdriven.fr\\\/overdriven\\\/index.php\\\/category\\\/reviews\\\/\",\"url\":\"https:\\\/\\\/overdriven.fr\\\/overdriven\\\/index.php\\\/category\\\/reviews\\\/\",\"name\":\"Archives des Reviews - Overdriven.fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/overdriven.fr\\\/overdriven\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/overdriven.fr\\\/overdriven\\\/index.php\\\/category\\\/reviews\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/overdriven.fr\\\/overdriven\\\/index.php\\\/category\\\/reviews\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/overdriven.fr\\\/overdriven\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reviews\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/overdriven.fr\\\/overdriven\\\/#website\",\"url\":\"https:\\\/\\\/overdriven.fr\\\/overdriven\\\/\",\"name\":\"Overdriven.fr\",\"description\":\"High-gain amps and guitar gear\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/overdriven.fr\\\/overdriven\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Reviews - Overdriven.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/overdriven.fr\/overdriven\/index.php\/category\/reviews\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des Reviews - Overdriven.fr","og_description":"review","og_url":"https:\/\/overdriven.fr\/overdriven\/index.php\/category\/reviews\/","og_site_name":"Overdriven.fr","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/overdriven.fr\/overdriven\/index.php\/category\/reviews\/","url":"https:\/\/overdriven.fr\/overdriven\/index.php\/category\/reviews\/","name":"Archives des Reviews - Overdriven.fr","isPartOf":{"@id":"https:\/\/overdriven.fr\/overdriven\/#website"},"breadcrumb":{"@id":"https:\/\/overdriven.fr\/overdriven\/index.php\/category\/reviews\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/overdriven.fr\/overdriven\/index.php\/category\/reviews\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/overdriven.fr\/overdriven\/"},{"@type":"ListItem","position":2,"name":"Reviews"}]},{"@type":"WebSite","@id":"https:\/\/overdriven.fr\/overdriven\/#website","url":"https:\/\/overdriven.fr\/overdriven\/","name":"Overdriven.fr","description":"High-gain amps and guitar gear","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/overdriven.fr\/overdriven\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/overdriven.fr\/overdriven\/index.php\/wp-json\/wp\/v2\/categories\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/overdriven.fr\/overdriven\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/overdriven.fr\/overdriven\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/overdriven.fr\/overdriven\/index.php\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}